{"id":83,"count":1,"description":"","link":"https:\/\/zaralogie.fr\/ar\/tag\/colostrum\/","name":"colostrum","slug":"colostrum","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.1.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>colostrum Archives - Zaralogie<\/title>\n<meta name=\"robots\"  content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\"  href=\"https:\/\/zaralogie.fr\/ar\/tag\/colostrum\/\" \/>\n<meta property=\"og:locale\"  content=\"ar_AR\" \/>\n<meta property=\"og:type\"  content=\"article\" \/>\n<meta property=\"og:title\"  content=\"colostrum Archives - Zaralogie\" \/>\n<meta property=\"og:url\"  content=\"https:\/\/zaralogie.fr\/ar\/tag\/colostrum\/\" \/>\n<meta property=\"og:site_name\" content=\"Zaralogie\" \/>\n<meta name=\"twitter:card\"  content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/zaralogie.fr\/ar\/#organization\",\"name\":\"Zaralogie-Logo\",\"url\":\"https:\/\/zaralogie.fr\/ar\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zaralogie.fr\/ar\/#logo\",\"inLanguage\":\"ar\",\"url\":\"https:\/\/zaralogie.fr\/wp-content\/uploads\/2020\/11\/logo4.png\",\"width\":261,\"height\":131,\"caption\":\"Zaralogie-Logo\"},\"image\":{\"@id\":\"https:\/\/zaralogie.fr\/ar\/#logo\"},\"location\":{\"@id\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/#local-place\"},\"address\":{\"@id\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/#local-place-address\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zaralogie.fr\/ar\/#website\",\"url\":\"https:\/\/zaralogie.fr\/ar\/\",\"name\":\"Zaralogie\",\"description\":\"Pensez Biologie et sant\\u00e9\",\"publisher\":{\"@id\":\"https:\/\/zaralogie.fr\/ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/zaralogie.fr\/ar\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ar\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/#webpage\",\"url\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/\",\"name\":\"colostrum Archives - Zaralogie\",\"isPartOf\":{\"@id\":\"https:\/\/zaralogie.fr\/ar\/#website\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zaralogie.fr\/tag\/colostrum\/\"]}]},{\"@type\":\"Place\",\"@id\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/#local-place\",\"address\":{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/zaralogie.fr\/tag\/colostrum\/#local-place-address\",\"streetAddress\":\"\",\"addressLocality\":\"\",\"postalCode\":\"\",\"addressRegion\":\"\",\"addressCountry\":\"\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"\",\"longitude\":\"\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/zaralogie.fr\/ar\/wp-json\/wp\/v2\/tags\/83"}],"collection":[{"href":"https:\/\/zaralogie.fr\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zaralogie.fr\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zaralogie.fr\/ar\/wp-json\/wp\/v2\/posts?tags=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}